{"id":7850,"date":"2023-07-03T18:35:46","date_gmt":"2023-07-03T16:35:46","guid":{"rendered":"https:\/\/openeurope.es\/projectes\/ready-teddy-go\/"},"modified":"2024-02-16T12:11:33","modified_gmt":"2024-02-16T11:11:33","slug":"ready-teddy-go","status":"publish","type":"projects","link":"https:\/\/openeurope.es\/es\/proyectos\/ready-teddy-go\/","title":{"rendered":"Ready Teddy, Go!"},"content":{"rendered":"","protected":false},"template":"","types-of-projects":[121],"topics":[93,109],"class_list":["post-7850","projects","type-projects","status-publish","hentry","types-of-projects-erasmus-ka2-es-2","topics-accesibilidad-e-inclusion","topics-inclusion-social"],"_wp_attached_file":null,"_wp_attachment_metadata":null,"_elementor_source_image_hash":null,"wpml_media_processed":null,"_elementor_is_screenshot":null,"litespeed-optimize-set":null,"_source_url":null,"naixement-cb":null,"telefon-cb":null,"email-cb":null,"participant-cb":null,"preferencia-cb":null,"observacions-cb":null,"descripcio-soc":null,"duracio-soc":null,"requisits-soc":null,"imatge-soc":null,"envato_tk_source_kit":null,"envato_tk_source_index":null,"envato_tk_manifest":null,"envato_tk_folder_name":null,"envato_tk_builder":null,"envato_tk_source_zip_url":null,"envato_elements_download_event":null,"_listing_data":null,"_listing_type":null,"_jet_engine_listing_css":null,"_build_layout":null,"_notifications":null,"_messages":null,"_form_data":null,"_captcha":null,"_preset":null,"_rendered_form":null,"_notifications_data":null,"_jf_preset":null,"_jf_actions":null,"_jf_messages":null,"_jf_recaptcha":null,"_jf_args":null,"_jf_validation":null,"_jet_sm_ready_style":null,"_jet_sm_style":null,"_jet_sm_controls_values":null,"_jet_sm_fonts_collection":null,"_jet_sm_fonts_links":null,"_content_type":null,"_conditions":null,"_relation_type":null,"_settings":null,"_styles":null,"_is_deps_ready":null,"_is_style_deps":null,"_is_script_deps":null,"_filter_label":null,"_active_label":null,"_filter_type":null,"_date_source":null,"_is_hierarchical":null,"_ih_source_map":null,"_data_source":null,"_query_builder_query":null,"_query_builder_value_prop":null,"_query_builder_label_prop":null,"_rating_options":null,"_rating_compare_operand":null,"_source_taxonomy":null,"_terms_relational_operator":null,"_source_post_type":null,"_glossary_id":null,"_glossary_notice":null,"_add_all_option":null,"_all_option_label":null,"_ability_deselect_radio":null,"_show_empty_terms":null,"_only_child":null,"_group_by_parent":null,"_source_custom_field":null,"_source_get_from_field_data":null,"_custom_field_source_plugin":null,"_source_manual_input":null,"_color_image_type":null,"_query_builder_color_prop":null,"_query_builder_image_prop":null,"_color_image_behavior":null,"_source_color_image_input":null,"_source_manual_input_range":null,"_placeholder":null,"_s_placeholder":null,"_is_custom_checkbox":null,"_s_by":null,"_date_format":null,"_date_from_placeholder":null,"_date_to_placeholder":null,"_date_period_type":null,"_date_period_datepicker_button_text":null,"_date_period_start_end_enabled":null,"_date_period_format":null,"_date_period_start_format":null,"_date_period_separator":null,"_date_period_end_format":null,"_range_inputs_enabled":null,"_values_prefix":null,"_values_suffix":null,"_values_thousand_sep":null,"_values_decimal_sep":null,"_values_decimal_num":null,"_source_min":null,"_source_max":null,"_source_step":null,"_source_callback":null,"_use_exclude_include":null,"_data_exclude_include":null,"_alphabet_behavior":null,"_alphabet_radio_deselect":null,"_alphabet_options":null,"_query_var":null,"_is_custom_query_var":null,"_custom_query_var":null,"_query_compare":null,"license":null,"_min_max_date_period_enabled":null,"_min_date_period":null,"_max_date_period":null,"_query_switcher_notice":null,"_query_builder_queries_to_switch":null,"_color_image_add_all_option":null,"_color_image_add_all_option_lael":null,"_color_image_add_all_option_image":null,"_color_image_ability_deselect_radio":null,"_range_inputs_separators_enabled":null,"_jet_template_conditions":null,"_jet_template_content_type":null,"_jet_template_type":null,"address_location":null,"url":null,"aeef8768d2ce7a376b7e0a52267e81f6_hash":null,"aeef8768d2ce7a376b7e0a52267e81f6_lat":null,"aeef8768d2ce7a376b7e0a52267e81f6_lng":null,"location-type":null,"portada":null,"d4a235027b7557695bebd0a2475a1472_hash":null,"d4a235027b7557695bebd0a2475a1472_lat":null,"d4a235027b7557695bebd0a2475a1472_lng":null,"ea932377d948cd3d3c1cdd87c17388cc_hash":null,"ea932377d948cd3d3c1cdd87c17388cc_lat":null,"ea932377d948cd3d3c1cdd87c17388cc_lng":null,"c569cbb83496252dcdd3254c58fcd76f_hash":null,"c569cbb83496252dcdd3254c58fcd76f_lat":null,"c569cbb83496252dcdd3254c58fcd76f_lng":null,"d5a90be7c93e1031900ebc1d0b651655_hash":null,"d5a90be7c93e1031900ebc1d0b651655_lat":null,"d5a90be7c93e1031900ebc1d0b651655_lng":null,"04701bbc89365067c32da2655d1a9285_hash":null,"04701bbc89365067c32da2655d1a9285_lat":null,"04701bbc89365067c32da2655d1a9285_lng":null,"87172944a73f0969ed1730028fde1c1e_hash":null,"87172944a73f0969ed1730028fde1c1e_lat":null,"87172944a73f0969ed1730028fde1c1e_lng":null,"b86ed6dd699a438c577ccd53b992928f_hash":null,"b86ed6dd699a438c577ccd53b992928f_lat":null,"b86ed6dd699a438c577ccd53b992928f_lng":null,"f43b41bb25bc966b9a73954eae904ed3_hash":null,"f43b41bb25bc966b9a73954eae904ed3_lat":null,"f43b41bb25bc966b9a73954eae904ed3_lng":null,"bb12555fdf0760dfc6d4acf4926b2686_hash":null,"bb12555fdf0760dfc6d4acf4926b2686_lat":null,"bb12555fdf0760dfc6d4acf4926b2686_lng":null,"90dda215b4bbb709ac61e7ad38c1db9c_hash":null,"90dda215b4bbb709ac61e7ad38c1db9c_lat":null,"90dda215b4bbb709ac61e7ad38c1db9c_lng":null,"366080b32ac22c58919b244856343488_hash":null,"366080b32ac22c58919b244856343488_lat":null,"366080b32ac22c58919b244856343488_lng":null,"6cd8c781167a3b10d922babd905fa874_hash":null,"6cd8c781167a3b10d922babd905fa874_lat":null,"6cd8c781167a3b10d922babd905fa874_lng":null,"0efa37c1689e9568fc0ca1a439ca08bd_hash":null,"0efa37c1689e9568fc0ca1a439ca08bd_lat":null,"0efa37c1689e9568fc0ca1a439ca08bd_lng":null,"98b209bae1187c4168a0d1d2054ba093_hash":null,"98b209bae1187c4168a0d1d2054ba093_lat":null,"98b209bae1187c4168a0d1d2054ba093_lng":null,"naixement-mb":null,"telefon-mb":null,"email-mb":null,"observacions-mb":null,"_menu_item_type":null,"_menu_item_menu_item_parent":null,"_menu_item_object_id":null,"_menu_item_object":null,"_menu_item_target":null,"_menu_item_classes":null,"_menu_item_xfn":null,"_menu_item_url":null,"_oembed_dfd94b239bcfd96edce4f0171e1197cd":null,"_oembed_time_dfd94b239bcfd96edce4f0171e1197cd":null,"_oembed_556810c4ded9970e21b49572efa870f8":null,"__elementor_forms_snapshot":null,"two_optimized_date":null,"naixement-psoc":null,"telefon-psoc":null,"email-psoc":null,"curs-interessat-psoc":null,"partner-adress":null,"partner-web":null,"partner-logo":null,"2e7b85251655c9f7f040744212245891_hash":null,"2e7b85251655c9f7f040744212245891_lat":null,"2e7b85251655c9f7f040744212245891_lng":null,"_pll_strings_translations":null,"informacio-general_tab":null,"informacio-general":null,"textos-projecte":null,"xarxes-socials":null,"link-web":null,"link-instagram":null,"link-facebook":null,"link-twitter":null,"link-linkedin":null,"partners-links":null,"partner1":null,"partner-1-link":null,"partner2":null,"partner-2-link":null,"partner3":null,"partner-3-link":null,"partner4":null,"partner-4-link":null,"partner5":null,"partner-5-link":null,"partner6":null,"partner-6-link":null,"partner7":null,"partner-7-link":null,"pdfs":null,"nom-boto-fitxer-1":null,"link-boto-fitxer-1":null,"general-information_accordion":"","general-information":"","project-number":"2021-1-PL01-KA220-SCH-000027809","sector":"School","type-of-project":"KA2","year-creation":"2021","start-year":"2021-11-01","year-completion":"2024-01-01","media_accordion":"","media":"","project-logo":{"id":3853,"url":"https:\/\/openeurope.es\/wp-content\/uploads\/2022\/11\/ReadyTeddyGo.png"},"program-logo":{"id":3633,"url":"https:\/\/openeurope.es\/wp-content\/uploads\/2023\/03\/logoProgramaUE.png"},"footer-image":"","project-information_accordion":"","project-information":"","p_description":"<p><span data-sheets-root=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El proyecto Ready Teddy Go! se enfoca en los alumnos con necesidades educativas especiales, a menudo excluidos de las clases tradicionales y asignados a clases especiales dentro de la misma escuela o a una escuela espec\u00edfica. Al llegar a la edad adulta, estos alumnos enfrentan discriminaci\u00f3n en varios aspectos de la vida, experimentando dificultades para establecer relaciones sociales y acceder a oportunidades profesionales. Con el fin de contrarrestar los riesgos asociados con esta discriminaci\u00f3n, el proyecto tiene como objetivo desarrollar habilidades clave y ampliar conocimientos a trav\u00e9s de un enfoque innovador. Para lograr esto, se crear\u00e1 un avatar llamado TEDDY, equipado con un sistema multimodal dise\u00f1ado para abordar las necesidades de aprendizaje y ense\u00f1anza espec\u00edficas de los j\u00f3venes estudiantes con necesidades educativas especiales. Este avatar ayudar\u00e1 a desplegar sus habilidades y potenciar sus cualidades.&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:33567683,&quot;3&quot;:{&quot;1&quot;:0},&quot;4&quot;:{&quot;1&quot;:2,&quot;2&quot;:14281427},&quot;9&quot;:0,&quot;10&quot;:1,&quot;11&quot;:3,&quot;12&quot;:0,&quot;15&quot;:&quot;Calibri&quot;,&quot;16&quot;:10,&quot;28&quot;:1}\">El proyecto Ready Teddy Go! se enfoca en los alumnos con necesidades educativas especiales, a menudo excluidos de las clases tradicionales y asignados a clases especiales dentro de la misma escuela o a una escuela espec\u00edfica. Al llegar a la edad adulta, estos alumnos enfrentan discriminaci\u00f3n en varios aspectos de la vida, experimentando dificultades para establecer relaciones sociales y acceder a oportunidades profesionales. Con el fin de contrarrestar los riesgos asociados con esta discriminaci\u00f3n, el proyecto tiene como objetivo desarrollar habilidades clave y ampliar conocimientos a trav\u00e9s de un enfoque innovador. Para lograr esto, se crear\u00e1 un avatar llamado TEDDY, equipado con un sistema multimodal dise\u00f1ado para abordar las necesidades de aprendizaje y ense\u00f1anza espec\u00edficas de los j\u00f3venes estudiantes con necesidades educativas especiales. Este avatar ayudar\u00e1 a desplegar sus habilidades y potenciar sus cualidades.<\/span><\/p>\n","p_objectives":"<p><span data-sheets-root=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Promover la inclusi\u00f3n y la diversidad en todos los \u00e1mbitos de la educaci\u00f3n.\\nAbordar la transformaci\u00f3n digital mediante el desarrollo de la preparaci\u00f3n digital para estudiantes con NEE y profesores\/educadores.\\nMejorar la adaptabilidad y capacidad de estudiantes y profesionales de la educaci\u00f3n.\\nPotenciar las habilidades sociales, c\u00edvicas y de alfabetizaci\u00f3n digital de los estudiantes con NEE.&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:33567683,&quot;3&quot;:{&quot;1&quot;:0},&quot;4&quot;:{&quot;1&quot;:2,&quot;2&quot;:14281427},&quot;9&quot;:0,&quot;10&quot;:1,&quot;11&quot;:3,&quot;12&quot;:0,&quot;15&quot;:&quot;Calibri&quot;,&quot;16&quot;:10,&quot;28&quot;:1}\">Promover la inclusi\u00f3n y la diversidad en todos los \u00e1mbitos de la educaci\u00f3n.<br \/>\nAbordar la transformaci\u00f3n digital mediante el desarrollo de la preparaci\u00f3n digital para estudiantes con NEE y profesores\/educadores.<br \/>\nMejorar la adaptabilidad y capacidad de estudiantes y profesionales de la educaci\u00f3n.<br \/>\nPotenciar las habilidades sociales, c\u00edvicas y de alfabetizaci\u00f3n digital de los estudiantes con NEE.<\/span><\/p>\n","p_results":"<p><span data-sheets-root=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;\u2022 E-Compendio: Lista de soluciones y pr\u00e1cticas existentes para promover competencias clave en alumnos con NEE.\\n\u2022 Curso de Formaci\u00f3n Online para Profesores y Educadores con directrices y consejos para padres de alumnos con NEE.\\n\u2022 TEDDY Avatar: Dirigida a alumnos con NEE de 9 a 14 a\u00f1os.\\n\u2022 Plataforma Electr\u00f3nica\\n&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:33567683,&quot;3&quot;:{&quot;1&quot;:0},&quot;4&quot;:{&quot;1&quot;:2,&quot;2&quot;:14281427},&quot;9&quot;:0,&quot;10&quot;:1,&quot;11&quot;:3,&quot;12&quot;:0,&quot;15&quot;:&quot;Calibri&quot;,&quot;16&quot;:10,&quot;28&quot;:1}\">\u2022 E-Compendio: Lista de soluciones y pr\u00e1cticas existentes para promover competencias clave en alumnos con NEE.<br \/>\n\u2022 Curso de Formaci\u00f3n Online para Profesores y Educadores con directrices y consejos para padres de alumnos con NEE.<br \/>\n\u2022 TEDDY Avatar: Dirigida a alumnos con NEE de 9 a 14 a\u00f1os.<br \/>\n\u2022 Plataforma Electr\u00f3nica<br \/>\n<\/span><\/p>\n","social-media_accordion":"","social-media":"","website":"https:\/\/readyteddygo.eu","instagram":"","facebook":"https:\/\/www.facebook.com\/ReadyTeddyGoProject","linkedin":"","twitter":"","tiktok":"","partners_accordion":"","partners":"","partner_fields":{"item-0":{"partner-name":"Politechnika Lodzka - Pol\u00f2nia","partner-url":"https:\/\/p.lodz.pl"},"item-1":{"partner-name":"Fundacja Instytut Re-Integracji Spolecznej - Pol\u00f2nia","partner-url":"https:\/\/fundacjairis.com"},"item-2":{"partner-name":"Fondazione Istituto dei Sordi di Torino ONLUS - It\u00e0lia","partner-url":"https:\/\/istitutosorditorino.org"},"item-3":{"partner-name":"A &amp; A Emphasys Interactive Solutions Ltd.  - Xipre","partner-url":"https:\/\/emphasyscentre.com"},"item-4":{"partner-name":"Associaci\u00f3 Programes Educatius Open Europe -  Espanya  ","partner-url":"https:\/\/openeurope.es"},"item-5":{"partner-name":"e-Nable Grecia - Gr\u00e8cia","partner-url":"https:\/\/enabling.gr"},"item-6":{"partner-name":"Sutrikusio intelekto zmoniu globos bendrija \"Vilniaus Viltis\" - Litu\u00e0nia","partner-url":"https:\/\/vilniausvitlis.lt"}},"testimonials_accordion":"","testimonials":"","testimonials_name":"","testimonials_description":"","testimonials_title":"","testimonials_avatar":"","buttons_accordion":"","buttons":"","button_1":"","button_1_url":"","button_2":"","button_2_url":"","_icl_lang_duplicate_of":null,"_wpcode_auto_insert":null,"_wpcode_auto_insert_number":null,"_wpcode_library_id":null,"_wpcode_conditional_logic_enabled":null,"_wpcode_priority":null,"_wpcode_note":null,"_wpcode_location_extra":null,"_wpcode_shortcode_attributes":null,"_wpcode_conditional_logic":null,"_eael_post_view_count":"662","ekit_post_views_count":"645","_edit_lock":"1708082319:6","_edit_last":"6","_wp_trash_meta_status":null,"_wp_trash_meta_time":null,"_wp_desired_post_slug":null,"_wpml_word_count":"{\"total\":6,\"to_translate\":{\"ca\":6,\"en\":6}}","_wpml_media_duplicate":"1","_wpml_media_featured":"1","_last_translation_edit_mode":"native-editor","_wp_old_slug":null,"_elementor_edit_mode":null,"_elementor_template_type":null,"_wp_page_template":null,"_elementor_page_settings":null,"_elementor_data":null,"_elementor_page_assets":[],"_elementor_version":null,"_elementor_pro_version":null,"_jet_sm_fonts_cache":null,"_elementor_elements_default_values":null,"_eael_custom_js":null,"_elementor_conditions":null,"_wpml_location_migration_done":null,"_elementor_controls_usage":null,"_jet_sm_is_processed":null,"_elementor_css":null,"_elementor_screenshot_failed":null,"_elementor_popup_display_settings":null,"_elementor_screenshot":null,"_elementor_source":null,"_eael_widget_elements":null,"_wp_old_date":null,"numero-projecte":null,"foto-programa":null,"descripcio-del-projecte":null,"objectius-del-projecte":null,"resultats-del-projecte":null,"_links":{"self":[{"href":"https:\/\/openeurope.es\/es\/wp-json\/wp\/v2\/projects\/7850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/openeurope.es\/es\/wp-json\/wp\/v2\/projects"}],"about":[{"href":"https:\/\/openeurope.es\/es\/wp-json\/wp\/v2\/types\/projects"}],"wp:attachment":[{"href":"https:\/\/openeurope.es\/es\/wp-json\/wp\/v2\/media?parent=7850"}],"wp:term":[{"taxonomy":"types-of-projects","embeddable":true,"href":"https:\/\/openeurope.es\/es\/wp-json\/wp\/v2\/types-of-projects?post=7850"},{"taxonomy":"topics","embeddable":true,"href":"https:\/\/openeurope.es\/es\/wp-json\/wp\/v2\/topics?post=7850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}